{"id":2273,"date":"2026-05-08T17:41:44","date_gmt":"2026-05-08T22:41:44","guid":{"rendered":"https:\/\/auratravelexperience.com\/?post_type=paquete&#038;p=2273"},"modified":"2026-07-01T17:08:42","modified_gmt":"2026-07-01T22:08:42","slug":"lago-sandoval-3-dias","status":"publish","type":"paquete","link":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/","title":{"rendered":"Lago Sandoval 3 dias: experi\u00eancia na Amaz\u00f4nia Peruana"},"content":{"rendered":"\n<h2 id=\"itinerario-115cc282-a43f-42d7-8fdf-2a7abdf202af\" class=\"wp-block-heading\">Roteiro Detalhado<\/h2>\n\n\n\n<div class=\"wp-block-advgb-accordions advgb-accordions-b5c41813-d609-4a42-890b-fb66b7e617eb advgb-accordion-wrapper\" data-collapsed=\"true\">\n<div class=\"wp-block-advgb-accordion-item advgb-accordion-item\" style=\"margin-bottom:0\"><div class=\"advgb-accordion-header\" style=\"background-color:#ffffff;color:#2e2e2e;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon accordion-state\"><svg class=\"advgb-icon-closed\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M16.59,8.59L12,13.17L7.41,8.59L6,10l6,6l6-6L16.59,8.59z\"><\/path><\/svg><svg class=\"advgb-icon-opened\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M7.41,15.41L12,10.83l4.59,4.58L18,14l-6-6l-6,6L7.41,15.41z\"><\/path><\/svg><\/span><h3 class=\"advgb-accordion-header-title\" style=\"color:inherit\"><strong>Dia 1 <\/strong>&#8211; Bem-vindo \u00e0 Amaz\u00f4nia Peruana<\/h3><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\">\n<p class=\"wp-block-paragraph\">Ao chegar ao aeroporto de Puerto Maldonado, nossa equipe o receber\u00e1 para dar in\u00edcio a esta aventura na floresta tropical peruana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de seguir para o lodge, voc\u00ea pode deixar parte da sua bagagem em nosso escrit\u00f3rio para uma viagem mais confort\u00e1vel. Em seguida, iremos para Puerto Bol\u00edvar, onde embarcaremos em um barco que nos levar\u00e1 pelo Rio Madre de Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O passeio de barco \u00e9 o seu primeiro contato com a Amaz\u00f4nia: vegeta\u00e7\u00e3o exuberante, o som de p\u00e1ssaros tropicais e a sensa\u00e7\u00e3o de entrar gradualmente em um mundo completamente diferente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao chegar ao lodge, voc\u00ea ser\u00e1 recebido com uma bebida refrescante feita com frutas locais. Ap\u00f3s se acomodar em seu bangal\u00f4 e desfrutar do almo\u00e7o, voc\u00ea ter\u00e1 tempo para relaxar e apreciar a natureza ao redor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Primeira Trilha na Selva<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 tarde, faremos uma caminhada guiada por trilhas amaz\u00f4nicas, onde aprenderemos sobre \u00e1rvores medicinais, plantas tropicais e algumas das esp\u00e9cies mais representativas da Madre de Dios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m visitaremos antigos acampamentos de seringueiros e garimpeiros de castanha-do-par\u00e1, atividades tradicionais que fazem parte da hist\u00f3ria econ\u00f4mica e cultural da Amaz\u00f4nia peruana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A caminhada dura aproximadamente duas horas e \u00e9 perfeita para come\u00e7ar a sentir a energia da selva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Saf\u00e1ri Noturno para Observa\u00e7\u00e3o de Jacar\u00e9s<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando a noite cai, a Amaz\u00f4nia se transforma completamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o jantar, faremos um passeio de barco noturno pelo rio para observar jacar\u00e9s e outras esp\u00e9cies que emergem \u00e0 noite. O sil\u00eancio da selva, o reflexo dos nossos olhos na \u00e1gua e os sons da floresta criam uma experi\u00eancia verdadeiramente especial. Refei\u00e7\u00f5es inclu\u00eddas: Almo\u00e7o, Jantar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pernoite<\/strong>: Lodge amaz\u00f4nico em meio \u00e0 natureza.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a573e0b36cc5&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573e0b38f6b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573e0b38f6b\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"3539\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/maldonado-viajes-819x1024.webp\" alt=\"\" class=\"wp-image-3539\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/maldonado-viajes-819x1024.webp 819w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/maldonado-viajes-240x300.webp 240w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/maldonado-viajes-768x960.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/maldonado-viajes.webp 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573e0b39b83&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573e0b39b83\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"3543\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-en-tambopata-819x1024.webp\" alt=\"\" class=\"wp-image-3543\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-en-tambopata-819x1024.webp 819w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-en-tambopata-240x300.webp 240w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-en-tambopata-768x960.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-en-tambopata.webp 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573e0b3a4c9&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573e0b3a4c9\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"3542\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/lago-sandoval-tours-819x1024.webp\" alt=\"\" class=\"wp-image-3542\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/lago-sandoval-tours-819x1024.webp 819w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/lago-sandoval-tours-240x300.webp 240w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/lago-sandoval-tours-768x960.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/lago-sandoval-tours.webp 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-accordion-item advgb-accordion-item\" style=\"margin-bottom:0\"><div class=\"advgb-accordion-header\" style=\"background-color:#ffffff;color:#2e2e2e;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon accordion-state\"><svg class=\"advgb-icon-closed\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M16.59,8.59L12,13.17L7.41,8.59L6,10l6,6l6-6L16.59,8.59z\"><\/path><\/svg><svg class=\"advgb-icon-opened\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M7.41,15.41L12,10.83l4.59,4.58L18,14l-6-6l-6,6L7.41,15.41z\"><\/path><\/svg><\/span><h3 class=\"advgb-accordion-header-title\" style=\"color:inherit\">Dia 2 &#8211; Expedi\u00e7\u00e3o ao Lago Sandoval<\/h3><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\">\n<p class=\"wp-block-paragraph\">Bem cedinho pela manh\u00e3, iniciaremos uma das experi\u00eancias mais impressionantes da viagem: uma <strong>visita ao Lago Sandoval<\/strong>, localizado dentro da <strong>Reserva Nacional Tambopata<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s uma bebida quente, come\u00e7aremos nossa jornada navegando pelo Rio Madre de Dios at\u00e9 chegarmos \u00e0 entrada da reserva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De l\u00e1, faremos uma caminhada cercados por \u00e1rvores gigantes, ra\u00edzes imensas e uma biodiversidade incr\u00edvel. Ao longo do caminho, poderemos observar aves tropicais, macacos e diversas esp\u00e9cies nativas da floresta amaz\u00f4nica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Navega\u00e7\u00e3o no Lago Sandoval<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao chegarmos ao lago, embarcaremos em pequenos barcos a remo para explorar tranquilamente este ecossistema \u00fanico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A paisagem \u00e9 simplesmente deslumbrante: \u00e1guas calmas, reflexos perfeitos da vegeta\u00e7\u00e3o e uma sensa\u00e7\u00e3o absoluta de paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com um pouco de sorte, poderemos observar lontras-gigantes, tartarugas, aves ex\u00f3ticas e outras esp\u00e9cies em seu habitat natural. Enquanto apreciamos a paisagem, tomaremos o caf\u00e9 da manh\u00e3 em meio a um dos cen\u00e1rios mais belos da Amaz\u00f4nia peruana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tarde de Relaxamento e Natureza<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o almo\u00e7o, visitaremos uma das torres de observa\u00e7\u00e3o do lodge, de onde teremos uma vista privilegiada da floresta tropical e suas copas imponentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00e1 o momento perfeito para contemplar o p\u00f4r do sol amaz\u00f4nico e se conectar com a tranquilidade do local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 noite, voc\u00ea poder\u00e1 descansar, aproveitar a piscina ou simplesmente relaxar ouvindo os sons da natureza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Refei\u00e7\u00f5es<\/strong> inclusas: Caf\u00e9 da manh\u00e3, Almo\u00e7o, Jantar <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pernoite<\/strong>: Lodge na Amaz\u00f4nia.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a573e0b3cf14&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573e0b3d70f&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573e0b3d70f\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"3551\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tambopata-tours-1-819x1024.webp\" alt=\"\" class=\"wp-image-3551\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tambopata-tours-1-819x1024.webp 819w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/tambopata-tours-1-240x300.webp 240w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/tambopata-tours-1-768x960.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/tambopata-tours-1.webp 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573e0b3e046&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573e0b3e046\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"3553\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/mirador-tambopata-819x1024.webp\" alt=\"\" class=\"wp-image-3553\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/mirador-tambopata-819x1024.webp 819w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/mirador-tambopata-240x300.webp 240w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/mirador-tambopata-768x960.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/mirador-tambopata.webp 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573e0b3e885&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573e0b3e885\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"3548\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-like-819x1024.webp\" alt=\"\" class=\"wp-image-3548\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-like-819x1024.webp 819w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-like-240x300.webp 240w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-like-768x960.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-like.webp 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-accordion-item advgb-accordion-item\" style=\"margin-bottom:0\"><div class=\"advgb-accordion-header\" style=\"background-color:#ffffff;color:#2e2e2e;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon accordion-state\"><svg class=\"advgb-icon-closed\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M16.59,8.59L12,13.17L7.41,8.59L6,10l6,6l6-6L16.59,8.59z\"><\/path><\/svg><svg class=\"advgb-icon-opened\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M7.41,15.41L12,10.83l4.59,4.58L18,14l-6-6l-6,6L7.41,15.41z\"><\/path><\/svg><\/span><h3 class=\"advgb-accordion-header-title\" style=\"color:inherit\">Dia 3 &#8211; Nascer do sol no barranco de argila dos papagaios e retorno<\/h3><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\">\n<p class=\"wp-block-paragraph\">Nosso \u00faltimo dia come\u00e7a antes do amanhecer com uma curta caminhada at\u00e9 um barranco de argila frequentado por papagaios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui, presenciaremos um dos espet\u00e1culos naturais mais incr\u00edveis da regi\u00e3o: dezenas de papagaios coloridos descendo para se alimentar da argila mineral, essencial para o seu metabolismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assistir ao nascer do sol enquanto a floresta tropical desperta lentamente \u00e9, sem d\u00favida, um daqueles momentos que ficam para sempre na mem\u00f3ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o caf\u00e9 da manh\u00e3, iniciaremos nossa viagem de volta para Puerto Maldonado. Antes de seguirmos para o aeroporto, faremos uma breve visita ao mercado local, onde descobriremos produtos t\u00edpicos da regi\u00e3o e teremos um vislumbre do cotidiano na Amaz\u00f4nia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, providenciaremos o traslado para o aeroporto para o embarque no voo de retorno ou para a continua\u00e7\u00e3o da sua viagem pelo Peru.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muitos viajantes continuam sua aventura explorando destinos como Machu Picchu, Cusco ou trilhas como a Trilha Salkantay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Refei\u00e7\u00f5es inclu\u00eddas<\/strong>: Caf\u00e9 da manh\u00e3<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a573e0b3f68d&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573e0b3fe76&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573e0b3fe76\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"3557\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/collpa-loros-819x1024.webp\" alt=\"\" class=\"wp-image-3557\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/collpa-loros-819x1024.webp 819w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/collpa-loros-240x300.webp 240w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/collpa-loros-768x960.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/collpa-loros.webp 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573e0b4080a&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573e0b4080a\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"3563\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-lake-peru-819x1024.webp\" alt=\"\" class=\"wp-image-3563\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-lake-peru-819x1024.webp 819w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-lake-peru-240x300.webp 240w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-lake-peru-768x960.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/sandoval-lake-peru.webp 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573e0b41480&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573e0b41480\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"3560\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/amanecer-tambopata-819x1024.webp\" alt=\"\" class=\"wp-image-3560\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/amanecer-tambopata-819x1024.webp 819w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/amanecer-tambopata-240x300.webp 240w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/amanecer-tambopata-768x960.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/amanecer-tambopata.webp 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns incluyecss is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong><strong>O que est\u00e1 inclu\u00eddo<\/strong><\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Recep\u00e7\u00e3o e traslados<\/li>\n\n\n\n<li>Transporte fluvial<\/li>\n\n\n\n<li>2 noites de hospedagem em um lodge na Amaz\u00f4nia<\/li>\n\n\n\n<li>Refei\u00e7\u00f5es conforme o itiner\u00e1rio<\/li>\n\n\n\n<li>Passeio ao Lago Sandoval<\/li>\n\n\n\n<li>Saf\u00e1ri noturno para observa\u00e7\u00e3o de jacar\u00e9s<\/li>\n\n\n\n<li>Visita a um barranco de argila frequentado por papagaios<\/li>\n\n\n\n<li>Guia profissional<\/li>\n\n\n\n<li>Taxas de entrada e permiss\u00f5es.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong><strong>O que n\u00e3o est\u00e1 inclu\u00eddo:<\/strong><\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Passagens a\u00e9reas nacionais e internacionais.<\/li>\n\n\n\n<li>Use repelente de insetos e protetor solar<\/li>\n\n\n\n<li>Leve uma capa de chuva leve<\/li>\n\n\n\n<li>C\u00e2mera ou bin\u00f3culos<\/li>\n\n\n\n<li>Cal\u00e7ado apropriado para caminhada<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns incluyecss is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">Recomenda\u00e7\u00f5es para viajar para a Amaz\u00f4nia Peruana<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Levar roupas leves e confort\u00e1veis<\/li>\n\n\n\n<li>Usar repelente e protetor solar<\/li>\n\n\n\n<li>Levar capa de chuva leve<\/li>\n\n\n\n<li>Levar c\u00e2mera fotogr\u00e1fica ou bin\u00f3culos<\/li>\n\n\n\n<li>Usar cal\u00e7ados adequados para caminhadas<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Perguntas Frequentes<\/h2>\n\n\n\n<div class=\"wp-block-advgb-accordions advgb-accordions-e3f08e50-aa4c-4964-8665-3d504c9b7f36 advgb-accordion-wrapper\" data-collapsed=\"true\">\n<div class=\"wp-block-advgb-accordion-item advgb-accordion-item\" style=\"margin-bottom:0\"><div class=\"advgb-accordion-header\" style=\"background-color:#ffffff;color:#2e2e2e;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon accordion-state\"><svg class=\"advgb-icon-closed\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M16.59,8.59L12,13.17L7.41,8.59L6,10l6,6l6-6L16.59,8.59z\"><\/path><\/svg><svg class=\"advgb-icon-opened\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M7.41,15.41L12,10.83l4.59,4.58L18,14l-6-6l-6,6L7.41,15.41z\"><\/path><\/svg><\/span><h3 class=\"advgb-accordion-header-title\" style=\"color:inherit\"><strong><strong><strong>1. Preciso de experi\u00eancia pr\u00e9via para este passeio?<\/strong><\/strong><\/strong><\/h3><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\">\n<p class=\"wp-block-paragraph\">&#8220;De forma alguma. Se voc\u00ea consegue caminhar em um parque ou na praia por 45 minutos, poder\u00e1 aproveitar o Lago Sandoval sem problemas. As trilhas s\u00e3o em sua maioria planas e caminhamos em um ritmo tranquilo, pois o objetivo n\u00e3o \u00e9 chegar rapidamente, mas sim parar e observar um macaco no topo de uma \u00e1rvore ou uma orqu\u00eddea escondida. \u00c9 uma aventura suave, planejada para o m\u00ednimo esfor\u00e7o e o m\u00e1ximo de encantamento.&#8221;<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-accordion-item advgb-accordion-item\" style=\"margin-bottom:0\"><div class=\"advgb-accordion-header\" style=\"background-color:#ffffff;color:#2e2e2e;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon accordion-state\"><svg class=\"advgb-icon-closed\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M16.59,8.59L12,13.17L7.41,8.59L6,10l6,6l6-6L16.59,8.59z\"><\/path><\/svg><svg class=\"advgb-icon-opened\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M7.41,15.41L12,10.83l4.59,4.58L18,14l-6-6l-6,6L7.41,15.41z\"><\/path><\/svg><\/span><h3 class=\"advgb-accordion-header-title\" style=\"color:inherit\"><strong><strong><strong>2. H\u00e1 animais para ver durante o passeio?<\/strong><\/strong><\/strong><\/h3><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\">\n<p class=\"wp-block-paragraph\">A floresta tropical n\u00e3o \u00e9 um zool\u00f3gico, e \u00e9 isso que a torna m\u00e1gica. Voc\u00ea ver\u00e1 vida em cada canto, desde borboletas Morpho azul-el\u00e9tricas at\u00e9 fam\u00edlias de macacos nos observando com curiosidade. Em rela\u00e7\u00e3o \u00e0s &#8220;estrelas&#8221;, como a lontra-de-rio ou o jacar\u00e9-a\u00e7u, temos uma taxa de avistamento extremamente alta gra\u00e7as ao conhecimento dos nossos guias sobre seus esconderijos favoritos, mas lembre-se: cada encontro \u00e9 um presente \u00fanico que a natureza nos concede naquele dia. Nenhum passeio \u00e9 igual ao outro.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-accordion-item advgb-accordion-item\" style=\"margin-bottom:0\"><div class=\"advgb-accordion-header\" style=\"background-color:#ffffff;color:#2e2e2e;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon accordion-state\"><svg class=\"advgb-icon-closed\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M16.59,8.59L12,13.17L7.41,8.59L6,10l6,6l6-6L16.59,8.59z\"><\/path><\/svg><svg class=\"advgb-icon-opened\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M7.41,15.41L12,10.83l4.59,4.58L18,14l-6-6l-6,6L7.41,15.41z\"><\/path><\/svg><\/span><h3 class=\"advgb-accordion-header-title\" style=\"color:inherit\"><strong><strong><strong>3. Como \u00e9 o clima em Puerto Maldonado?<\/strong><\/strong><\/strong><\/h3><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\">\n<p class=\"wp-block-paragraph\">Puerto Maldonado \u00e9 o abra\u00e7o acolhedor da Amaz\u00f4nia. Sim, tem um clima tropical (quente e \u00famido), mas \u00e9 justamente isso que permite que a floresta tropical seja t\u00e3o exuberante. N\u00e3o se preocupe com o calor: o design da nossa pousada permite a circula\u00e7\u00e3o natural do ar e as atividades s\u00e3o programadas durante as horas mais frescas (manh\u00e3 e tarde). Al\u00e9m disso, n\u00e3o h\u00e1 nada como uma chuva amaz\u00f4nica para refrescar o ar e ver a floresta ganhar vida em um instante.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-accordion-item advgb-accordion-item\" style=\"margin-bottom:0\"><div class=\"advgb-accordion-header\" style=\"background-color:#ffffff;color:#2e2e2e;border-style:solid;border-width:1px;border-radius:2px\"><span class=\"advgb-accordion-header-icon accordion-state\"><svg class=\"advgb-icon-closed\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M16.59,8.59L12,13.17L7.41,8.59L6,10l6,6l6-6L16.59,8.59z\"><\/path><\/svg><svg class=\"advgb-icon-opened\" fill=\"#2e2e2e\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\"><path opacity=\"0.87\" fill=\"none\" d=\"M24,24H0L0,0l24,0V24z\"><\/path><path d=\"M7.41,15.41L12,10.83l4.59,4.58L18,14l-6-6l-6,6L7.41,15.41z\"><\/path><\/svg><\/span><h3 class=\"advgb-accordion-header-title\" style=\"color:inherit\"><strong><strong><strong><strong>4. E os mosquitos?<\/strong><\/strong><\/strong><\/strong><\/h3><\/div><div class=\"advgb-accordion-body\" style=\"border-style:solid !important;border-width:1px !important;border-color:undefined !important;border-top:none !important;border-radius:2px !important\">\n<p class=\"wp-block-paragraph\">Ser\u00edamos desonestos se diss\u00e9ssemos que n\u00e3o h\u00e1 nenhum \u2014 afinal, \u00e9 a casa deles! No entanto, com um bom repelente de insetos org\u00e2nico e usando roupas leves de manga comprida, eles se tornam uma preocupa\u00e7\u00e3o menor. Al\u00e9m disso, a presen\u00e7a de insetos \u00e9 consideravelmente reduzida na superf\u00edcie do Lago Sandoval, permitindo que voc\u00ea aprecie a paisagem em completa tranquilidade.<\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Viva uma das melhores aventuras na natureza do Peru.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A floresta tropical peruana tem uma maneira \u00fanica de surpreender cada viajante. Caminhar entre \u00e1rvores gigantes, navegar por lagos cercados por floresta tropical e acordar com os sons da Amaz\u00f4nia tornam esta viagem uma experi\u00eancia inesquec\u00edvel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reserve agora seu passeio de 3 dias pelo Lago Sandoval e descubra a magia da Amaz\u00f4nia peruana.<\/p>\n","protected":false},"author":2,"featured_media":2192,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"class_list":["post-2273","paquete","type-paquete","status-publish","has-post-thumbnail","hentry"],"acf":{"intro_paquete":"H\u00e1 lugares que simplesmente visita\u2026 e outros que sente profundamente.\r\n\r\nA Amaz\u00f3nia peruana \u00e9 um deles.\r\n\r\nEsta viagem ao Lago Sandoval foi pensada para aqueles que desejam desligar-se do ru\u00eddo da vida quotidiana e reconectar-se com a natureza na sua forma mais pura.\r\n\r\nNavegar\u00e1 pelo Rio Madre de Dios, caminhar\u00e1 entre \u00e1rvores gigantes, observar\u00e1 a vida selvagem no seu habitat natural e despertar\u00e1 com os sons da floresta tropical mais biodiversa do planeta.\r\n\r\nDurante tr\u00eas dias, desfrutar\u00e1 de uma experi\u00eancia aut\u00eantica em Puerto Maldonado, combinando aventura tranquila, conforto e momentos que ficar\u00e3o para sempre gravados na sua mem\u00f3ria.\r\n\r\nIdeal para quem procura complementar a sua viagem a Machu Picchu e Cusco com uma experi\u00eancia \u00fanica na floresta tropical Madre de Dios.\r\n\r\n<strong>Resumo da Viagem<\/strong>\r\n<ul>\r\n \t<li><strong>Destino<\/strong>: Puerto Maldonado \u2013 Lago Sandoval \u2013 Reserva Nacional Tambopata<\/li>\r\n \t<li><strong>Dura\u00e7\u00e3o<\/strong>: 3 dias \/ 2 noites<\/li>\r\n \t<li><strong>Tipo de experi\u00eancia<\/strong>: Natureza, aventura e relaxamento<\/li>\r\n \t<li><strong>Ideal para<\/strong>: Casais, fam\u00edlias, viajantes amantes da natureza e fot\u00f3grafos<\/li>\r\n \t<li><strong>N\u00edvel f\u00edsico<\/strong>: Moderado<\/li>\r\n \t<li><strong>Hospedagem<\/strong>: Lodge amaz\u00f4nico cercado pela floresta tropical<\/li>\r\n<\/ul>","video_paquete":["Cusco Ciudad","Valle Sagrado","Laguna Humantay","Monta\u00f1a de Colores","Lima","Ica Paracas"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lago Sandoval 3 dias | Amaz\u00f4nia Peruana- Aura Travel Experience<\/title>\n<meta name=\"description\" content=\"Descubra Lago Sandoval em 3 dias com uma experi\u00eancia na Amaz\u00f4nia Peruana, incluindo fauna silvestre, passeios de barco e natureza exuberante.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lago Sandoval 3 dias | Amaz\u00f4nia Peruana- Aura Travel Experience\" \/>\n<meta property=\"og:description\" content=\"Descubra Lago Sandoval em 3 dias com uma experi\u00eancia na Amaz\u00f4nia Peruana, incluindo fauna silvestre, passeios de barco e natureza exuberante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Aura Travel Experience\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuraTravelExperience\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T22:08:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-lago-sandoval.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/pacotes\\\/lago-sandoval-3-dias\\\/\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/pacotes\\\/lago-sandoval-3-dias\\\/\",\"name\":\"Lago Sandoval 3 dias | Amaz\u00f4nia Peruana- Aura Travel Experience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/pacotes\\\/lago-sandoval-3-dias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/pacotes\\\/lago-sandoval-3-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/tour-lago-sandoval.webp\",\"datePublished\":\"2026-05-08T22:41:44+00:00\",\"dateModified\":\"2026-07-01T22:08:42+00:00\",\"description\":\"Descubra Lago Sandoval em 3 dias com uma experi\u00eancia na Amaz\u00f4nia Peruana, incluindo fauna silvestre, passeios de barco e natureza exuberante.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/pacotes\\\/lago-sandoval-3-dias\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/pacotes\\\/lago-sandoval-3-dias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/pacotes\\\/lago-sandoval-3-dias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/tour-lago-sandoval.webp\",\"contentUrl\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/tour-lago-sandoval.webp\",\"width\":2000,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/pacotes\\\/lago-sandoval-3-dias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lago Sandoval 3 dias: experi\u00eancia na Amaz\u00f4nia Peruana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/\",\"name\":\"Aura Travel Experiences\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#organization\",\"name\":\"Aura Travel Experiences\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/cropped-Logo-Aura-nuevo-png.webp\",\"contentUrl\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/cropped-Logo-Aura-nuevo-png.webp\",\"width\":1149,\"height\":521,\"caption\":\"Aura Travel Experiences\"},\"image\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuraTravelExperience\",\"https:\\\/\\\/www.tiktok.com\\\/@aura_travel_experience\",\"https:\\\/\\\/www.instagram.com\\\/auratravel.experience\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@AuraTravelExperience\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lago Sandoval 3 dias | Amaz\u00f4nia Peruana- Aura Travel Experience","description":"Descubra Lago Sandoval em 3 dias com uma experi\u00eancia na Amaz\u00f4nia Peruana, incluindo fauna silvestre, passeios de barco e natureza exuberante.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/","og_locale":"pt_BR","og_type":"article","og_title":"Lago Sandoval 3 dias | Amaz\u00f4nia Peruana- Aura Travel Experience","og_description":"Descubra Lago Sandoval em 3 dias com uma experi\u00eancia na Amaz\u00f4nia Peruana, incluindo fauna silvestre, passeios de barco e natureza exuberante.","og_url":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/","og_site_name":"Aura Travel Experience","article_publisher":"https:\/\/www.facebook.com\/AuraTravelExperience","article_modified_time":"2026-07-01T22:08:42+00:00","og_image":[{"width":2000,"height":900,"url":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-lago-sandoval.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/","url":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/","name":"Lago Sandoval 3 dias | Amaz\u00f4nia Peruana- Aura Travel Experience","isPartOf":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/#primaryimage"},"image":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-lago-sandoval.webp","datePublished":"2026-05-08T22:41:44+00:00","dateModified":"2026-07-01T22:08:42+00:00","description":"Descubra Lago Sandoval em 3 dias com uma experi\u00eancia na Amaz\u00f4nia Peruana, incluindo fauna silvestre, passeios de barco e natureza exuberante.","breadcrumb":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/#primaryimage","url":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-lago-sandoval.webp","contentUrl":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-lago-sandoval.webp","width":2000,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/auratravelexperience.com\/pt-br\/pacotes\/lago-sandoval-3-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auratravelexperience.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Lago Sandoval 3 dias: experi\u00eancia na Amaz\u00f4nia Peruana"}]},{"@type":"WebSite","@id":"https:\/\/auratravelexperience.com\/pt-br\/#website","url":"https:\/\/auratravelexperience.com\/pt-br\/","name":"Aura Travel Experiences","description":"","publisher":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auratravelexperience.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/auratravelexperience.com\/pt-br\/#organization","name":"Aura Travel Experiences","url":"https:\/\/auratravelexperience.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auratravelexperience.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/cropped-Logo-Aura-nuevo-png.webp","contentUrl":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/cropped-Logo-Aura-nuevo-png.webp","width":1149,"height":521,"caption":"Aura Travel Experiences"},"image":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuraTravelExperience","https:\/\/www.tiktok.com\/@aura_travel_experience","https:\/\/www.instagram.com\/auratravel.experience\/","https:\/\/www.youtube.com\/@AuraTravelExperience"]}]}},"featured_img":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/tour-lago-sandoval.webp","coauthors":[],"author_meta":{"author_link":"https:\/\/auratravelexperience.com\/pt-br\/author\/admin_editor\/","display_name":"Aura Travel Experiences"},"relative_dates":{"created":"Publicado 2 meses atr\u00e1s","modified":"Atualizado 2 semanas atr\u00e1s"},"absolute_dates":{"created":"Publicado em 8 de maio de 2026","modified":"Atualizado em 1 de julho de 2026"},"absolute_dates_time":{"created":"Publicado em 8 de maio de 2026 17:41","modified":"Atualizado em 1 de julho de 2026 17:08"},"featured_img_caption":"","tax_additional":{"translation_priority":{"linked":["<a href=\"https:\/\/auratravelexperience.com\/es\/?taxonomy=translation_priority&#038;term=opcional\" class=\"advgb-post-tax-term\">Opcional<\/a>","<a href=\"https:\/\/auratravelexperience.com\/es\/?taxonomy=translation_priority&#038;term=opcional\" class=\"advgb-post-tax-term\">Opcional<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Opcional<\/span>","<span class=\"advgb-post-tax-term\">Opcional<\/span>"],"slug":"translation_priority","name":"Prioridades de tradu\u00e7\u00e3o"}},"series_order":"","_links":{"self":[{"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/paquete\/2273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/paquete"}],"about":[{"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/types\/paquete"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/media\/2192"}],"wp:attachment":[{"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}