{"id":874,"date":"2026-04-16T18:16:26","date_gmt":"2026-04-16T23:16:26","guid":{"rendered":"https:\/\/auratravelexperience.com\/trekking\/salkantay-trek-to-machu-picchu-4-days\/"},"modified":"2026-05-22T16:10:09","modified_gmt":"2026-05-22T21:10:09","slug":"trilha-salkantay-machu-picchu-4-dias","status":"publish","type":"trekking","link":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/","title":{"rendered":"Trilha Salkantay a Machu Picchu 4 Dias"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:65%\">\n<p class=\"wp-block-paragraph\">A Trilha Salkantay a Machu Picchu em 4 dias \u00e9 uma das rotas de trekking mais impressionantes do Peru e uma das melhores alternativas ao cl\u00e1ssico Caminho Inca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa aventura leva voc\u00ea por uma incr\u00edvel variedade de paisagens: desde imponentes montanhas nevadas como o Salkantay, passando por lagoas de \u00e1guas turquesa, at\u00e9 descer para a selva alta cheia de vegeta\u00e7\u00e3o tropical. Em poucos dias, voc\u00ea experimentar\u00e1 mudan\u00e7as dr\u00e1sticas de clima, altitude e ecossistemas, tornando este trek uma experi\u00eancia \u00fanica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o percurso, voc\u00ea alcan\u00e7ar\u00e1 o ponto mais alto no <strong>Abra Salkantay<\/strong>, a mais de 4.600 metros de altitude, onde poder\u00e1 desfrutar de vistas espetaculares dos Andes. Depois, o caminho continua em dire\u00e7\u00e3o \u00e0 floresta nublada, atravessando comunidades locais, planta\u00e7\u00f5es de caf\u00e9 e trilhas menos movimentadas, permitindo uma conex\u00e3o mais aut\u00eantica com a natureza e a cultura andina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, o trek termina com a visita guiada \u00e0 majestosa cidadela de <strong>Machu Picchu<\/strong>, onde voc\u00ea conhecer\u00e1 a hist\u00f3ria e os mist\u00e9rios de uma das maravilhas do mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por que escolher o Salkantay Trek 4 dias?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Oferece paisagens mais diversas e menos movimentadas<\/li>\n\n\n\n<li>Ideal para viajantes que buscam aventura e desafio<\/li>\n\n\n\n<li>Combina natureza, cultura e uma experi\u00eancia aut\u00eantica<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:35%\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a573f06006e1&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a573f06006e1\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/salkantay-Trek-Map-to-Machu-Picchu.webp\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n<\/div>\n\n\n    <!-- Facts grid -->\n                                                            <div class=\"grid grid-cols-2 sm:grid-cols-6 gap-3 my-8 mb-10\">\n                                                    <div class=\"border border-gray-200 rounded-2xl px-4 py-5 text-center hover:border-primary\/40 hover:bg-[#f7fdf9] transition-all bg-white\">\n                                <svg class=\"w-6 h-6 text-primary mx-auto mb-2\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.7\" viewBox=\"0 0 24 24\">\n                                    <path d=\"M8 7V3m8 4V3m-9 8h10M5 21h14a2 2 0 002-2V7a2 2 0 00-2-2H5a2 2 0 00-2 2v12a2 2 0 002 2z\" \/>\n                                <\/svg>\n                                <div class=\"text-[10px] font-bold uppercase tracking-widest text-gray-400 mb-1\">DURA\u00c7\u00c3O<\/div>\n                                <div class=\"text-sm font-bold text-gray-900\">4 dias \u00b7 3 noites<\/div>\n                            <\/div>\n                                                    <div class=\"border border-gray-200 rounded-2xl px-4 py-5 text-center hover:border-primary\/40 hover:bg-[#f7fdf9] transition-all bg-white\">\n                                <svg class=\"w-6 h-6 text-primary mx-auto mb-2\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.7\" viewBox=\"0 0 24 24\">\n                                    <path d=\"M13 10V3L4 14h7v7l9-11h-7z\" \/>\n                                <\/svg>\n                                <div class=\"text-[10px] font-bold uppercase tracking-widest text-gray-400 mb-1\">DIFICULDADE<\/div>\n                                <div class=\"text-sm font-bold text-gray-900\">Moderado<\/div>\n                            <\/div>\n                                                    <div class=\"border border-gray-200 rounded-2xl px-4 py-5 text-center hover:border-primary\/40 hover:bg-[#f7fdf9] transition-all bg-white\">\n                                <svg class=\"w-6 h-6 text-primary mx-auto mb-2\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.7\" viewBox=\"0 0 24 24\">\n                                    <path d=\"M17.657 16.657L13.414 20.9a1.998 1.998 0 01-2.827 0l-4.244-4.243a8 8 0 1111.314 0zM15 11a3 3 0 11-6 0 3 3 0 016 0z\" \/>\n                                <\/svg>\n                                <div class=\"text-[10px] font-bold uppercase tracking-widest text-gray-400 mb-1\">ALTITUDE M\u00c1X.<\/div>\n                                <div class=\"text-sm font-bold text-gray-900\">4,215 m.s.n.m.<\/div>\n                            <\/div>\n                                                    <div class=\"border border-gray-200 rounded-2xl px-4 py-5 text-center hover:border-primary\/40 hover:bg-[#f7fdf9] transition-all bg-white\">\n                                <svg class=\"w-6 h-6 text-primary mx-auto mb-2\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.7\" viewBox=\"0 0 24 24\">\n                                    <path d=\"M9 20l-5.447-2.724A1 1 0 013 16.382V5.618a1 1 0 011.447-.894L9 7m0 13l6-3m-6 3V7m6 10l4.553 2.276A1 1 0 0021 18.382V7.618a1 1 0 00-.553-.894L15 4m0 13V4m0 0L9 7\" \/>\n                                <\/svg>\n                                <div class=\"text-[10px] font-bold uppercase tracking-widest text-gray-400 mb-1\">DIST\u00c2NCIA<\/div>\n                                <div class=\"text-sm font-bold text-gray-900\">43 Km<\/div>\n                            <\/div>\n                                                    <div class=\"border border-gray-200 rounded-2xl px-4 py-5 text-center hover:border-primary\/40 hover:bg-[#f7fdf9] transition-all bg-white\">\n                                <svg class=\"w-6 h-6 text-primary mx-auto mb-2\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.7\" viewBox=\"0 0 24 24\">\n                                    <path d=\"M17 20h5v-2a3 3 0 00-5.356-1.857M17 20H7m10 0v-2c0-.656-.126-1.283-.356-1.857M7 20H2v-2a3 3 0 015.356-1.857M7 20v-2c0-.656.126-1.283.356-1.857m0 0a5.002 5.002 0 019.288 0\" \/>\n                                <\/svg>\n                                <div class=\"text-[10px] font-bold uppercase tracking-widest text-gray-400 mb-1\">GRUPO M\u00c1XIMO<\/div>\n                                <div class=\"text-sm font-bold text-gray-900\">8 pessoas<\/div>\n                            <\/div>\n                                                    <div class=\"border border-gray-200 rounded-2xl px-4 py-5 text-center hover:border-primary\/40 hover:bg-[#f7fdf9] transition-all bg-white\">\n                                <svg class=\"w-6 h-6 text-primary mx-auto mb-2\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.7\" viewBox=\"0 0 24 24\">\n                                    <path d=\"M5 3v4M3 5h4M6 17v4m-2-2h4m5-16l2.286 6.857L21 12l-5.714 2.143L13 21l-2.286-6.857L5 12l5.714-2.143L13 3z\" \/>\n                                <\/svg>\n                                <div class=\"text-[10px] font-bold uppercase tracking-widest text-gray-400 mb-1\">ESTA\u00c7\u00c3O IDEAL<\/div>\n                                <div class=\"text-sm font-bold text-gray-900\">Abr &#8211; Oct<\/div>\n                            <\/div>\n                                            <\/div>\n                    \n\n\n<h2 class=\"wp-block-heading\">GALERIA DE FOTOS<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-4 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2434\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trilha-1024x768.webp\" alt=\"\" class=\"wp-image-2434\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trilha-1024x768.webp 1024w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trilha-300x225.webp 300w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trilha-768x576.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trilha.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2440\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trek-1024x768.webp\" alt=\"\" class=\"wp-image-2440\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trek-1024x768.webp 1024w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trek-300x225.webp 300w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trek-768x576.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-trek.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2436\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/salkantay-machupicchu-1024x768.webp\" alt=\"\" class=\"wp-image-2436\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/salkantay-machupicchu-1024x768.webp 1024w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/salkantay-machupicchu-300x225.webp 300w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/salkantay-machupicchu-768x576.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/salkantay-machupicchu.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2431\" src=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-4-dias-1024x768.webp\" alt=\"\" class=\"wp-image-2431\" srcset=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-4-dias-1024x768.webp 1024w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-4-dias-300x225.webp 300w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-4-dias-768x576.webp 768w, https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-4-dias.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n\n\n<section class=\"py-8 bg-white mb-10\" id=\"itinerary\">\n    <div class=\"\">\n\n        <!-- Cabecera -->\n        <div class=\"mb-10\">\n                            <span class=\"text-[10px] font-bold tracking-[3px] uppercase text-gold\">\n                    Dia ap\u00f3s dia                <\/span>\n            \n                            <h2 class=\"font-display font-extrabold text-gray-900 text-2xl md:text-3xl mt-1\">\n                    Dia ap\u00f3s dia                <\/h2>\n            \n                            <p class=\"text-gray-500 text-sm mt-2\">\n                                    <\/p>\n                    <\/div>\n\n        <!-- Acorde\u00f3n -->\n                    <div class=\"space-y-3\">\n                                    <div class=\"border border-gray-200 rounded-2xl overflow-hidden\">\n\n                        <button\n                            class=\"acc-btn w-full flex items-center gap-4 px-6 py-5 text-left hover:bg-gray-50 transition-colors\"\n                            type=\"button\"\n                            onclick=\"this.classList.toggle('active');this.nextElementSibling.classList.toggle('open')\"\n                        >\n                            <!-- N\u00famero del d\u00eda -->\n                            <div\n                                class=\"flex-shrink-0 w-10 h-10 rounded-full flex items-center justify-center text-white text-sm font-extrabold\"\n                                style=\"background:#0A3D2E\"\n                            >\n                                01                            <\/div>\n\n                            <!-- T\u00edtulo + subt\u00edtulo -->\n                            <div class=\"flex-1 min-w-0\">\n                                <h3 class=\"font-bold !text-gray-900 !text-base !m-0\">Cusco \u2013 Mollepata \u2013 Soraypampa \u2013 Lagoa Humantay<\/h3>\n                                                                    <div class=\"text-xs text-gray-400 mt-0.5\">Dist\u00e2ncia: 15 km, Tempo de caminhada: 6 \u2013 7 horas, Altitude m\u00e1xima: 4.200 m (Lagoa Humantay), Dificuldade: Moderada<\/div>\n                                                            <\/div>\n\n                            <!-- Chevron -->\n                            <svg class=\"acc-icon w-5 h-5 text-gray-400 flex-shrink-0\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" viewBox=\"0 0 24 24\">\n                                <path d=\"M19 9l-7 7-7-7\" \/>\n                            <\/svg>\n                        <\/button>\n\n                        <!-- Cuerpo -->\n                        <div class=\"acc-body\">\n                            <div class=\"px-6 pb-6 border-t border-gray-100\">\n\n                                                                    <div class=\"prose prose-sm text-gray-700 max-w-none mt-5 mb-5 leading-relaxed\">\n                                        <p>Come\u00e7amos cedo com a coleta no seu hotel em Cusco e seguimos viagem at\u00e9 Mollepata, onde tomaremos caf\u00e9 da manh\u00e3 antes de continuar at\u00e9 Challacancha, ponto inicial da caminhada.<\/p>\n<p>A primeira parte do trekking \u00e9 progressiva, ideal para aclimata\u00e7\u00e3o. Caminharemos at\u00e9 Soraypampa, cercados por vistas impressionantes de montanhas nevadas como Salkantay e Humantay.<\/p>\n<p>\u00c0 tarde, faremos a caminhada at\u00e9 a <strong>Lagoa Humantay<\/strong>, um dos cen\u00e1rios mais ic\u00f4nicos do trek, com \u00e1guas turquesa cercadas por geleiras.<\/p>\n<p>Passamos a noite em Soraypampa.<\/p>\n                                    <\/div>\n                                \n                                <!-- Badges din\u00e1micos -->\n                                                                    <div class=\"flex flex-wrap gap-3\">\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Dist\u00e2ncia: 15 km                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#fef9ec] text-amber-700\">\n                                                Tempo de caminhada: 6 \u2013 7 horas                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Altitude m\u00e1xima: 4.200 m (Lagoa Humantay)                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#fef9ec] text-amber-700\">\n                                                Dificuldade: Moderada                                            <\/span>\n                                                                            <\/div>\n                                                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"border border-gray-200 rounded-2xl overflow-hidden\">\n\n                        <button\n                            class=\"acc-btn w-full flex items-center gap-4 px-6 py-5 text-left hover:bg-gray-50 transition-colors\"\n                            type=\"button\"\n                            onclick=\"this.classList.toggle('active');this.nextElementSibling.classList.toggle('open')\"\n                        >\n                            <!-- N\u00famero del d\u00eda -->\n                            <div\n                                class=\"flex-shrink-0 w-10 h-10 rounded-full flex items-center justify-center text-white text-sm font-extrabold\"\n                                style=\"background:#1a6b52\"\n                            >\n                                02                            <\/div>\n\n                            <!-- T\u00edtulo + subt\u00edtulo -->\n                            <div class=\"flex-1 min-w-0\">\n                                <h3 class=\"font-bold !text-gray-900 !text-base !m-0\">Soraypampa \u2013 Abra Salkantay \u2013 Collpapampa<\/h3>\n                                                                    <div class=\"text-xs text-gray-400 mt-0.5\">Dist\u00e2ncia: 19 km, Tempo de caminhada: 9 \u2013 10 horas, Altitude m\u00e1xima: 4.650 m, Altitude do acampamento: 2.700 m aprox., Dificuldade: Alta<\/div>\n                                                            <\/div>\n\n                            <!-- Chevron -->\n                            <svg class=\"acc-icon w-5 h-5 text-gray-400 flex-shrink-0\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" viewBox=\"0 0 24 24\">\n                                <path d=\"M19 9l-7 7-7-7\" \/>\n                            <\/svg>\n                        <\/button>\n\n                        <!-- Cuerpo -->\n                        <div class=\"acc-body\">\n                            <div class=\"px-6 pb-6 border-t border-gray-100\">\n\n                                                                    <div class=\"prose prose-sm text-gray-700 max-w-none mt-5 mb-5 leading-relaxed\">\n                                        <p>Este \u00e9 o dia mais desafiador do trek.<\/p>\n<p>Come\u00e7amos cedo com uma subida constante at\u00e9 o ponto mais alto: o Abra Salkantay (4.650 m), cercado por imponentes montanhas nevadas.<\/p>\n<p>A partir daqui, iniciamos uma longa descida em dire\u00e7\u00e3o \u00e0 floresta nublada, onde a paisagem muda drasticamente: de montanhas frias para \u00e1reas mais quentes e verdes.<\/p>\n<p>Ap\u00f3s o almo\u00e7o em Chaullay, continuamos at\u00e9 Collpapampa, onde passaremos a noite.<\/p>\n                                    <\/div>\n                                \n                                <!-- Badges din\u00e1micos -->\n                                                                    <div class=\"flex flex-wrap gap-3\">\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Dist\u00e2ncia: 19 km                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#fef9ec] text-amber-700\">\n                                                Tempo de caminhada: 9 \u2013 10 horas                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Altitude m\u00e1xima: 4.650 m                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#fef9ec] text-amber-700\">\n                                                Altitude do acampamento: 2.700 m aprox.                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Dificuldade: Alta                                            <\/span>\n                                                                            <\/div>\n                                                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"border border-gray-200 rounded-2xl overflow-hidden\">\n\n                        <button\n                            class=\"acc-btn w-full flex items-center gap-4 px-6 py-5 text-left hover:bg-gray-50 transition-colors\"\n                            type=\"button\"\n                            onclick=\"this.classList.toggle('active');this.nextElementSibling.classList.toggle('open')\"\n                        >\n                            <!-- N\u00famero del d\u00eda -->\n                            <div\n                                class=\"flex-shrink-0 w-10 h-10 rounded-full flex items-center justify-center text-white text-sm font-extrabold\"\n                                style=\"background:#2d8a6e\"\n                            >\n                                03                            <\/div>\n\n                            <!-- T\u00edtulo + subt\u00edtulo -->\n                            <div class=\"flex-1 min-w-0\">\n                                <h3 class=\"font-bold !text-gray-900 !text-base !m-0\">Collpapampa \u2013 Wi\u00f1aypoco \u2013 Granadilla \u2013 Hidrel\u00e9trica \u2013 \u00c1guas Calientes<\/h3>\n                                                                    <div class=\"text-xs text-gray-400 mt-0.5\">Dist\u00e2ncia: 10\u201312 km (caminhada), Tempo de caminhada: 5 \u2013 6 horas, Tempo de transporte: 1h30, Altitude m\u00e1xima: 2.650 m (Wi\u00f1aypoco), Altitude final: 2.000 m (\u00c1guas Calientes), Dificuldade: Moderada, Clima: Quente e \u00famido (presen\u00e7a de mosquitos)<\/div>\n                                                            <\/div>\n\n                            <!-- Chevron -->\n                            <svg class=\"acc-icon w-5 h-5 text-gray-400 flex-shrink-0\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" viewBox=\"0 0 24 24\">\n                                <path d=\"M19 9l-7 7-7-7\" \/>\n                            <\/svg>\n                        <\/button>\n\n                        <!-- Cuerpo -->\n                        <div class=\"acc-body\">\n                            <div class=\"px-6 pb-6 border-t border-gray-100\">\n\n                                                                    <div class=\"prose prose-sm text-gray-700 max-w-none mt-5 mb-5 leading-relaxed\">\n                                        <p>Ap\u00f3s um caf\u00e9 da manh\u00e3 cedo, iniciamos a caminhada descendo pela floresta nublada, uma das \u00e1reas mais biodiversas de todo o trekking. Durante o percurso, voc\u00ea poder\u00e1 observar uma grande variedade de flora, como orqu\u00eddeas, brom\u00e9lias e bomareas, al\u00e9m de aves e, ocasionalmente, fauna local.<\/p>\n<p>Ao longo do caminho, passaremos por pequenas comunidades como Wi\u00f1aypoco e Granadilla, onde voc\u00ea ter\u00e1 a oportunidade de interagir brevemente com fam\u00edlias locais e conhecer seu estilo de vida na selva alta.<\/p>\n<p>A partir deste ponto, seguiremos de transporte at\u00e9 a Hidrel\u00e9trica, onde almo\u00e7aremos. Depois, continuamos o trajeto final at\u00e9 \u00c1guas Calientes, caminhando ao lado da ferrovia em um ambiente tropical ou, opcionalmente, pegando o trem (n\u00e3o inclu\u00eddo).<\/p>\n<p>Ao chegar em <strong>\u00c1guas Calientes<\/strong>, faremos o check-in na hospedagem para descansar antes da visita a <strong>Machu Picchu<\/strong> no dia seguinte.<\/p>\n                                    <\/div>\n                                \n                                <!-- Badges din\u00e1micos -->\n                                                                    <div class=\"flex flex-wrap gap-3\">\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Dist\u00e2ncia: 10\u201312 km (caminhada)                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#fef9ec] text-amber-700\">\n                                                Tempo de caminhada: 5 \u2013 6 horas                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Tempo de transporte: 1h30                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#fef9ec] text-amber-700\">\n                                                Altitude m\u00e1xima: 2.650 m (Wi\u00f1aypoco)                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Altitude final: 2.000 m (\u00c1guas Calientes)                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#fef9ec] text-amber-700\">\n                                                Dificuldade: Moderada                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Clima: Quente e \u00famido (presen\u00e7a de mosquitos)                                            <\/span>\n                                                                            <\/div>\n                                                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                                    <div class=\"border border-gray-200 rounded-2xl overflow-hidden\">\n\n                        <button\n                            class=\"acc-btn w-full flex items-center gap-4 px-6 py-5 text-left hover:bg-gray-50 transition-colors\"\n                            type=\"button\"\n                            onclick=\"this.classList.toggle('active');this.nextElementSibling.classList.toggle('open')\"\n                        >\n                            <!-- N\u00famero del d\u00eda -->\n                            <div\n                                class=\"flex-shrink-0 w-10 h-10 rounded-full flex items-center justify-center text-white text-sm font-extrabold\"\n                                style=\"background:#c9a84c\"\n                            >\n                                04                            <\/div>\n\n                            <!-- T\u00edtulo + subt\u00edtulo -->\n                            <div class=\"flex-1 min-w-0\">\n                                <h3 class=\"font-bold !text-gray-900 !text-base !m-0\">\u00c1guas Calientes \u2013 Machu Picchu \u2013 Cusco<\/h3>\n                                                                    <div class=\"text-xs text-gray-400 mt-0.5\">Dist\u00e2ncia: 3\u20136 km (dependendo da op\u00e7\u00e3o), Tempo de caminhada: 1 \u2013 2 horas (opcional), Altitude m\u00e1xima: 2.430 m (Machu Picchu), Altitude de \u00c1guas Calientes: 2.000 m, Dificuldade: Baixa<\/div>\n                                                            <\/div>\n\n                            <!-- Chevron -->\n                            <svg class=\"acc-icon w-5 h-5 text-gray-400 flex-shrink-0\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2.5\" viewBox=\"0 0 24 24\">\n                                <path d=\"M19 9l-7 7-7-7\" \/>\n                            <\/svg>\n                        <\/button>\n\n                        <!-- Cuerpo -->\n                        <div class=\"acc-body\">\n                            <div class=\"px-6 pb-6 border-t border-gray-100\">\n\n                                                                    <div class=\"prose prose-sm text-gray-700 max-w-none mt-5 mb-5 leading-relaxed\">\n                                        <p>O dia mais esperado finalmente chegou. Ap\u00f3s o esfor\u00e7o realizado durante o trekking, visitaremos a majestosa cidadela de Machu Picchu.<\/p>\n<p>Bem cedo pela manh\u00e3, seguimos at\u00e9 a esta\u00e7\u00e3o de \u00f4nibus para subir at\u00e9 Machu Picchu e chegar ao amanhecer, um dos momentos mais impressionantes para apreciar o local com menos visitantes.<\/p>\n<p>Uma vez dentro, faremos uma visita guiada onde voc\u00ea conhecer\u00e1 em profundidade a hist\u00f3ria, arquitetura e mist\u00e9rios da civiliza\u00e7\u00e3o inca. Visitaremos os principais setores do santu\u00e1rio, incluindo templos, terra\u00e7os, \u00e1reas cerimoniais e residenciais.<\/p>\n<p>Ao final do tour, voc\u00ea ter\u00e1 tempo livre para caminhar por conta pr\u00f3pria, tirar fotos ou simplesmente aproveitar a energia \u00fanica do lugar.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Opcional: Huayna Picchu ou Montanha Machu Picchu<\/strong><\/p>\n<p>A visita a essas montanhas n\u00e3o est\u00e1 inclu\u00edda no trek e tem custo adicional. Devido \u00e0 alta demanda e disponibilidade limitada, recomendamos reservar com anteced\u00eancia para garantir o ingresso.<\/p>\n<p>Essas caminhadas oferecem vistas panor\u00e2micas espetaculares de Machu Picchu e s\u00e3o ideais para quem busca uma experi\u00eancia mais completa e desafiadora.<\/p>\n<p>Posteriormente, desceremos at\u00e9 \u00c1guas Calientes para almo\u00e7ar (por conta pr\u00f3pria) e, \u00e0 tarde, embarcaremos no trem de retorno a <strong>Cusco<\/strong>.<\/p>\n                                    <\/div>\n                                \n                                <!-- Badges din\u00e1micos -->\n                                                                    <div class=\"flex flex-wrap gap-3\">\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Dist\u00e2ncia: 3\u20136 km (dependendo da op\u00e7\u00e3o)                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#fef9ec] text-amber-700\">\n                                                Tempo de caminhada: 1 \u2013 2 horas (opcional),                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Altitude m\u00e1xima: 2.430 m (Machu Picchu)                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#fef9ec] text-amber-700\">\n                                                Altitude de \u00c1guas Calientes: 2.000 m                                            <\/span>\n                                                                                    <span class=\"inline-flex items-center rounded-full px-3 py-1.5 text-xs font-semibold bg-[#f0f9f4] text-primary\">\n                                                Dificuldade: Baixa                                            <\/span>\n                                                                            <\/div>\n                                                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        \n    <\/div>\n<\/section>\n\n\n\n<h2 class=\"wp-block-heading\">Inclui e n\u00e3o Inclui<\/h2>\n\n\n\n<div class=\"wp-block-columns incluyecss is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">inclui<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Transporte do seu hotel em Cusco at\u00e9 Mollepata (Challacancha)<\/li>\n\n\n\n<li>Transporte de Granadilla at\u00e9 a esta\u00e7\u00e3o Hidrel\u00e9trica<\/li>\n\n\n\n<li>\u00d4nibus tur\u00edstico de subida de \u00c1guas Calientes a Machu Picchu<\/li>\n\n\n\n<li>Trem tur\u00edstico de \u00c1guas Calientes at\u00e9 Ollantaytambo + transporte de retorno a Cusco<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>2 noites em domos de camping (primeira e segunda noite)<\/li>\n\n\n\n<li>1 noite em hotel em \u00c1guas Calientes<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Entrada para o Parque Nacional Salkantay<\/li>\n\n\n\n<li>Entrada para a cidadela de Machu Picchu<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Guia profissional bil\u00edngue (espanhol e ingl\u00eas)<\/li>\n\n\n\n<li>Cozinheiro profissional e assistente<\/li>\n\n\n\n<li>Arrieros e mulas para transporte de equipamentos<\/li>\n\n\n\n<li>Cavalo para transportar at\u00e9 7 kg de bagagem pessoal por cliente<\/li>\n\n\n\n<li>Cavalo de emerg\u00eancia durante o trek<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Caf\u00e9s da manh\u00e3, almo\u00e7os, jantares e snacks durante o trekking<\/li>\n\n\n\n<li>Op\u00e7\u00e3o vegetariana dispon\u00edvel sem custo adicional<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Kit de primeiros socorros<\/strong>&nbsp;&nbsp;<\/li>\n\n\n\n<li>Cilindro de oxig\u00eanio para emerg\u00eancias<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading\">N\u00e3o inclui<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Caf\u00e9 da manh\u00e3 do primeiro dia<\/li>\n\n\n\n<li>Almo\u00e7o do \u00faltimo dia em \u00c1guas Calientes<\/li>\n\n\n\n<li>Segundo \u00f4nibus de descida de Machu Picchu (opcional)<\/li>\n\n\n\n<li>Saco de dormir (dispon\u00edvel para aluguel)<\/li>\n\n\n\n<li>Bast\u00f5es de trekking (opcionais)<\/li>\n\n\n\n<li>Trem opcional da Hidrel\u00e9trica at\u00e9 \u00c1guas Calientes<\/li>\n\n\n\n<li>Seguro de viagem<\/li>\n\n\n\n<li>Gorjetas para a equipe (opcional)<\/li>\n\n\n\n<li>Despesas pessoais<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<script type=\"application\/ld+json\">\n{\n    \"@context\": \"https:\/\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Sobre o Desafio e a Altitude: Terei problemas com a altitude? (Vamos falar sobre a altitude)\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Para ser sincero: a subida do Passo Salkantay (4.650 m) \u00e9 definitivamente percept\u00edvel. N\u00e3o vamos dizer que \u00e9 f\u00e1cil, mas tamb\u00e9m n\u00e3o \u00e9 imposs\u00edvel. A chave \u00e9 a aclimata\u00e7\u00e3o. Recomendamos estar em Cusco pelo menos 2 dias antes de come\u00e7ar. Sempre levamos oxig\u00eanio e um kit de primeiros socorros de alta qualidade, mas o melhor a fazer \u00e9 relaxar e apreciar a paisagem.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Qu\u00e3o \\\"em forma\\\" preciso ser para manter o ritmo?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"A trilha de 4 dias do Passo Salkantay \u00e9 um desafio de moderado a alto. O segundo dia \u00e9 o mais intenso, pois subimos e descemos bastante. Se voc\u00ea caminha regularmente ou vai \u00e0 academia algumas vezes por semana, ficar\u00e1 bem. N\u00e3o \u00e9 uma corrida; o importante \u00e9 manter um ritmo constante. Suas pernas agradecer\u00e3o em Machu Picchu!\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Preciso carregar minha mala inteira durante a trilha?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"De jeito nenhum! Queremos que voc\u00ea aprecie a vista, n\u00e3o que sofra com o peso. Inclu\u00edmos um cavaleiro e mulas que carregar\u00e3o at\u00e9 7 kg dos seus pertences pessoais. Voc\u00ea s\u00f3 precisa levar sua mochila pequena com o essencial: \u00e1gua, lanches, c\u00e2mera e corta-vento.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Que roupas devo levar?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"O clima nos Andes \u00e9 imprevis\u00edvel. Em um \u00fanico dia, voc\u00ea pode ir do frio congelante do Passo Salkantay ao calor tropical da selva alta. O segredo \u00e9 se vestir em camadas:\\n\\nUma camada base respir\u00e1vel.\\nAlgo quente (fleece ou pluma).\\nUma camada imperme\u00e1vel (caso as nuvens resolvam aparecer).\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Como \u00e9 a comida nas montanhas?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Esque\u00e7a a comida industrializada. Nossos cozinheiros fazem m\u00e1gica no cora\u00e7\u00e3o dos Andes. Voc\u00ea desfrutar\u00e1 de caf\u00e9s da manh\u00e3 energizantes, almo\u00e7os nutritivos e jantares quentes que far\u00e3o voc\u00ea se sentir em casa. Se voc\u00ea for vegano, intolerante ao gl\u00faten ou tiver alguma alergia, por favor, nos avise; adoramos personalizar o card\u00e1pio para garantir que voc\u00ea tenha bastante energia.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Dormiremos em barracas comuns?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Queremos que voc\u00ea descanse de verdade. \u00c9 por isso que usamos domos ou acampamentos especialmente configurados que oferecem maior conforto e prote\u00e7\u00e3o contra as intemp\u00e9ries do que uma barraca de trekking convencional. Queremos que voc\u00ea contemple as estrelas, mas tamb\u00e9m que durma aquecido.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Por que escolher 4 dias em vez de 5?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"O roteiro de 4 dias \u00e9 ideal se voc\u00ea tem pouco tempo ou prefere um ritmo um pouco mais din\u00e2mico. Visitamos os mesmos pontos tur\u00edsticos deslumbrantes (Lagoa Humantay e o Passo Abra), mas otimizamos o trecho na selva. \u00c9 a dose perfeita de adrenalina e recompensa.\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Eu realmente verei o nascer do sol em Machu Picchu?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"Esse \u00e9 o plano. Sa\u00edmos de Aguas Calientes bem cedo para estarmos entre os primeiros a entrar. Observar as nuvens se dissiparem e revelarem a cidadela \u00e9 uma daquelas experi\u00eancias que arrepiam.\"\n            }\n        }\n    ]\n}<\/script>\n\n<!-- ======================== BLOQUE FAQs ======================== -->\n<section class=\"aura-faqs-block py-3\" id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca\">\n  <div class=\"\">\n\n    <!-- Encabezado -->\n        <div class=\"mb-10\">\n            <h2 class=\"text-3xl font-bold font-display text-gray-900 mb-3\">\n        Perguntas frequentes      <\/h2>\n                  <p class=\"text-gray-500 text-base leading-relaxed\">\n        Responderemos a todas as suas perguntas antes de voc\u00ea reservar sua viagem.      <\/p>\n          <\/div>\n    \n    <!-- Acordeones -->\n    \n        <div class=\"flex flex-col mx-auto\">\n              <div class=\"aura-faq-item border border-gray-200 rounded-xl overflow-hidden transition-shadow hover:shadow-md bg-white mb-3\"\n             data-faq-item>\n\n          <!-- Bot\u00f3n pregunta -->\n          <button\n            type=\"button\"\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-0\"\n            aria-expanded=\"false\"\n            aria-controls=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-0\"\n            class=\"aura-faq-btn w-full flex items-center justify-between gap-4 px-5 py-4 text-left font-semibold text-gray-900 text-[15px] leading-snug transition-colors duration-200 focus:outline-none\"\n            style=\"\">\n            <span class=\"flex items-start gap-3\">\n              <span class=\"mt-0.5 flex-shrink-0 w-6 h-6 rounded-full flex items-center justify-center text-white text-xs font-bold\"\n                    style=\"background:#0A3D2E;min-width:1.5rem\">\n                1              <\/span>\n              <span>Sobre o Desafio e a Altitude: Terei problemas com a altitude? (Vamos falar sobre a altitude)<\/span>\n            <\/span>\n            <!-- \u00cdcono chevron -->\n            <svg class=\"aura-faq-icon flex-shrink-0 transition-transform duration-300 \"\n                 width=\"20\" height=\"20\" fill=\"none\" stroke=\"#9ca3af\"\n                 stroke-width=\"2.2\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M19 9l-7 7-7-7\"\/>\n            <\/svg>\n          <\/button>\n\n          <!-- Panel respuesta -->\n          <div\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-0\"\n            role=\"region\"\n            aria-labelledby=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-0\"\n            class=\"aura-faq-panel\"\n            style=\"overflow:hidden;transition:max-height .35s ease,opacity .3s ease;max-height:0;opacity:0;\">\n            <div class=\"px-5 pb-5 pt-1 border-t border-gray-100\">\n              <div class=\"aura-faq-content text-gray-600 text-[14.5px] leading-relaxed pl-9\">\n                <p>Para ser sincero: a subida do Passo Salkantay (4.650 m) \u00e9 definitivamente percept\u00edvel. N\u00e3o vamos dizer que \u00e9 f\u00e1cil, mas tamb\u00e9m n\u00e3o \u00e9 imposs\u00edvel. A chave \u00e9 a aclimata\u00e7\u00e3o. Recomendamos estar em Cusco pelo menos 2 dias antes de come\u00e7ar. Sempre levamos oxig\u00eanio e um kit de primeiros socorros de alta qualidade, mas o melhor a fazer \u00e9 relaxar e apreciar a paisagem.<\/p>\n              <\/div>\n            <\/div>\n          <\/div>\n\n        <\/div>\n                <div class=\"aura-faq-item border border-gray-200 rounded-xl overflow-hidden transition-shadow hover:shadow-md bg-white mb-3\"\n             data-faq-item>\n\n          <!-- Bot\u00f3n pregunta -->\n          <button\n            type=\"button\"\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-1\"\n            aria-expanded=\"false\"\n            aria-controls=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-1\"\n            class=\"aura-faq-btn w-full flex items-center justify-between gap-4 px-5 py-4 text-left font-semibold text-gray-900 text-[15px] leading-snug transition-colors duration-200 focus:outline-none\"\n            style=\"\">\n            <span class=\"flex items-start gap-3\">\n              <span class=\"mt-0.5 flex-shrink-0 w-6 h-6 rounded-full flex items-center justify-center text-white text-xs font-bold\"\n                    style=\"background:#0A3D2E;min-width:1.5rem\">\n                2              <\/span>\n              <span>Qu\u00e3o &quot;em forma&quot; preciso ser para manter o ritmo?<\/span>\n            <\/span>\n            <!-- \u00cdcono chevron -->\n            <svg class=\"aura-faq-icon flex-shrink-0 transition-transform duration-300 \"\n                 width=\"20\" height=\"20\" fill=\"none\" stroke=\"#9ca3af\"\n                 stroke-width=\"2.2\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M19 9l-7 7-7-7\"\/>\n            <\/svg>\n          <\/button>\n\n          <!-- Panel respuesta -->\n          <div\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-1\"\n            role=\"region\"\n            aria-labelledby=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-1\"\n            class=\"aura-faq-panel\"\n            style=\"overflow:hidden;transition:max-height .35s ease,opacity .3s ease;max-height:0;opacity:0;\">\n            <div class=\"px-5 pb-5 pt-1 border-t border-gray-100\">\n              <div class=\"aura-faq-content text-gray-600 text-[14.5px] leading-relaxed pl-9\">\n                <p>A trilha de 4 dias do Passo Salkantay \u00e9 um desafio de moderado a alto. O segundo dia \u00e9 o mais intenso, pois subimos e descemos bastante. Se voc\u00ea caminha regularmente ou vai \u00e0 academia algumas vezes por semana, ficar\u00e1 bem. N\u00e3o \u00e9 uma corrida; o importante \u00e9 manter um ritmo constante. Suas pernas agradecer\u00e3o em Machu Picchu!<\/p>\n              <\/div>\n            <\/div>\n          <\/div>\n\n        <\/div>\n                <div class=\"aura-faq-item border border-gray-200 rounded-xl overflow-hidden transition-shadow hover:shadow-md bg-white mb-3\"\n             data-faq-item>\n\n          <!-- Bot\u00f3n pregunta -->\n          <button\n            type=\"button\"\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-2\"\n            aria-expanded=\"false\"\n            aria-controls=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-2\"\n            class=\"aura-faq-btn w-full flex items-center justify-between gap-4 px-5 py-4 text-left font-semibold text-gray-900 text-[15px] leading-snug transition-colors duration-200 focus:outline-none\"\n            style=\"\">\n            <span class=\"flex items-start gap-3\">\n              <span class=\"mt-0.5 flex-shrink-0 w-6 h-6 rounded-full flex items-center justify-center text-white text-xs font-bold\"\n                    style=\"background:#0A3D2E;min-width:1.5rem\">\n                3              <\/span>\n              <span>Preciso carregar minha mala inteira durante a trilha?<\/span>\n            <\/span>\n            <!-- \u00cdcono chevron -->\n            <svg class=\"aura-faq-icon flex-shrink-0 transition-transform duration-300 \"\n                 width=\"20\" height=\"20\" fill=\"none\" stroke=\"#9ca3af\"\n                 stroke-width=\"2.2\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M19 9l-7 7-7-7\"\/>\n            <\/svg>\n          <\/button>\n\n          <!-- Panel respuesta -->\n          <div\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-2\"\n            role=\"region\"\n            aria-labelledby=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-2\"\n            class=\"aura-faq-panel\"\n            style=\"overflow:hidden;transition:max-height .35s ease,opacity .3s ease;max-height:0;opacity:0;\">\n            <div class=\"px-5 pb-5 pt-1 border-t border-gray-100\">\n              <div class=\"aura-faq-content text-gray-600 text-[14.5px] leading-relaxed pl-9\">\n                <p>De jeito nenhum! Queremos que voc\u00ea aprecie a vista, n\u00e3o que sofra com o peso. Inclu\u00edmos um cavaleiro e mulas que carregar\u00e3o at\u00e9 7 kg dos seus pertences pessoais. Voc\u00ea s\u00f3 precisa levar sua mochila pequena com o essencial: \u00e1gua, lanches, c\u00e2mera e corta-vento.<\/p>\n              <\/div>\n            <\/div>\n          <\/div>\n\n        <\/div>\n                <div class=\"aura-faq-item border border-gray-200 rounded-xl overflow-hidden transition-shadow hover:shadow-md bg-white mb-3\"\n             data-faq-item>\n\n          <!-- Bot\u00f3n pregunta -->\n          <button\n            type=\"button\"\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-3\"\n            aria-expanded=\"false\"\n            aria-controls=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-3\"\n            class=\"aura-faq-btn w-full flex items-center justify-between gap-4 px-5 py-4 text-left font-semibold text-gray-900 text-[15px] leading-snug transition-colors duration-200 focus:outline-none\"\n            style=\"\">\n            <span class=\"flex items-start gap-3\">\n              <span class=\"mt-0.5 flex-shrink-0 w-6 h-6 rounded-full flex items-center justify-center text-white text-xs font-bold\"\n                    style=\"background:#0A3D2E;min-width:1.5rem\">\n                4              <\/span>\n              <span>Que roupas devo levar?<\/span>\n            <\/span>\n            <!-- \u00cdcono chevron -->\n            <svg class=\"aura-faq-icon flex-shrink-0 transition-transform duration-300 \"\n                 width=\"20\" height=\"20\" fill=\"none\" stroke=\"#9ca3af\"\n                 stroke-width=\"2.2\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M19 9l-7 7-7-7\"\/>\n            <\/svg>\n          <\/button>\n\n          <!-- Panel respuesta -->\n          <div\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-3\"\n            role=\"region\"\n            aria-labelledby=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-3\"\n            class=\"aura-faq-panel\"\n            style=\"overflow:hidden;transition:max-height .35s ease,opacity .3s ease;max-height:0;opacity:0;\">\n            <div class=\"px-5 pb-5 pt-1 border-t border-gray-100\">\n              <div class=\"aura-faq-content text-gray-600 text-[14.5px] leading-relaxed pl-9\">\n                <p>O clima nos Andes \u00e9 imprevis\u00edvel. Em um \u00fanico dia, voc\u00ea pode ir do frio congelante do Passo Salkantay ao calor tropical da selva alta. O segredo \u00e9 se vestir em camadas:<\/p>\n<ul>\n<li>Uma camada base respir\u00e1vel.<\/li>\n<li>Algo quente (fleece ou pluma).<\/li>\n<li>Uma camada imperme\u00e1vel (caso as nuvens resolvam aparecer).<\/li>\n<\/ul>\n              <\/div>\n            <\/div>\n          <\/div>\n\n        <\/div>\n                <div class=\"aura-faq-item border border-gray-200 rounded-xl overflow-hidden transition-shadow hover:shadow-md bg-white mb-3\"\n             data-faq-item>\n\n          <!-- Bot\u00f3n pregunta -->\n          <button\n            type=\"button\"\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-4\"\n            aria-expanded=\"false\"\n            aria-controls=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-4\"\n            class=\"aura-faq-btn w-full flex items-center justify-between gap-4 px-5 py-4 text-left font-semibold text-gray-900 text-[15px] leading-snug transition-colors duration-200 focus:outline-none\"\n            style=\"\">\n            <span class=\"flex items-start gap-3\">\n              <span class=\"mt-0.5 flex-shrink-0 w-6 h-6 rounded-full flex items-center justify-center text-white text-xs font-bold\"\n                    style=\"background:#0A3D2E;min-width:1.5rem\">\n                5              <\/span>\n              <span>Como \u00e9 a comida nas montanhas?<\/span>\n            <\/span>\n            <!-- \u00cdcono chevron -->\n            <svg class=\"aura-faq-icon flex-shrink-0 transition-transform duration-300 \"\n                 width=\"20\" height=\"20\" fill=\"none\" stroke=\"#9ca3af\"\n                 stroke-width=\"2.2\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M19 9l-7 7-7-7\"\/>\n            <\/svg>\n          <\/button>\n\n          <!-- Panel respuesta -->\n          <div\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-4\"\n            role=\"region\"\n            aria-labelledby=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-4\"\n            class=\"aura-faq-panel\"\n            style=\"overflow:hidden;transition:max-height .35s ease,opacity .3s ease;max-height:0;opacity:0;\">\n            <div class=\"px-5 pb-5 pt-1 border-t border-gray-100\">\n              <div class=\"aura-faq-content text-gray-600 text-[14.5px] leading-relaxed pl-9\">\n                <p>Esque\u00e7a a comida industrializada. Nossos cozinheiros fazem m\u00e1gica no cora\u00e7\u00e3o dos Andes. Voc\u00ea desfrutar\u00e1 de caf\u00e9s da manh\u00e3 energizantes, almo\u00e7os nutritivos e jantares quentes que far\u00e3o voc\u00ea se sentir em casa. Se voc\u00ea for vegano, intolerante ao gl\u00faten ou tiver alguma alergia, por favor, nos avise; adoramos personalizar o card\u00e1pio para garantir que voc\u00ea tenha bastante energia.<\/p>\n              <\/div>\n            <\/div>\n          <\/div>\n\n        <\/div>\n                <div class=\"aura-faq-item border border-gray-200 rounded-xl overflow-hidden transition-shadow hover:shadow-md bg-white mb-3\"\n             data-faq-item>\n\n          <!-- Bot\u00f3n pregunta -->\n          <button\n            type=\"button\"\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-5\"\n            aria-expanded=\"false\"\n            aria-controls=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-5\"\n            class=\"aura-faq-btn w-full flex items-center justify-between gap-4 px-5 py-4 text-left font-semibold text-gray-900 text-[15px] leading-snug transition-colors duration-200 focus:outline-none\"\n            style=\"\">\n            <span class=\"flex items-start gap-3\">\n              <span class=\"mt-0.5 flex-shrink-0 w-6 h-6 rounded-full flex items-center justify-center text-white text-xs font-bold\"\n                    style=\"background:#0A3D2E;min-width:1.5rem\">\n                6              <\/span>\n              <span>Dormiremos em barracas comuns?<\/span>\n            <\/span>\n            <!-- \u00cdcono chevron -->\n            <svg class=\"aura-faq-icon flex-shrink-0 transition-transform duration-300 \"\n                 width=\"20\" height=\"20\" fill=\"none\" stroke=\"#9ca3af\"\n                 stroke-width=\"2.2\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M19 9l-7 7-7-7\"\/>\n            <\/svg>\n          <\/button>\n\n          <!-- Panel respuesta -->\n          <div\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-5\"\n            role=\"region\"\n            aria-labelledby=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-5\"\n            class=\"aura-faq-panel\"\n            style=\"overflow:hidden;transition:max-height .35s ease,opacity .3s ease;max-height:0;opacity:0;\">\n            <div class=\"px-5 pb-5 pt-1 border-t border-gray-100\">\n              <div class=\"aura-faq-content text-gray-600 text-[14.5px] leading-relaxed pl-9\">\n                <p>Queremos que voc\u00ea descanse de verdade. \u00c9 por isso que usamos domos ou acampamentos especialmente configurados que oferecem maior conforto e prote\u00e7\u00e3o contra as intemp\u00e9ries do que uma barraca de trekking convencional. Queremos que voc\u00ea contemple as estrelas, mas tamb\u00e9m que durma aquecido.<\/p>\n              <\/div>\n            <\/div>\n          <\/div>\n\n        <\/div>\n                <div class=\"aura-faq-item border border-gray-200 rounded-xl overflow-hidden transition-shadow hover:shadow-md bg-white mb-3\"\n             data-faq-item>\n\n          <!-- Bot\u00f3n pregunta -->\n          <button\n            type=\"button\"\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-6\"\n            aria-expanded=\"false\"\n            aria-controls=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-6\"\n            class=\"aura-faq-btn w-full flex items-center justify-between gap-4 px-5 py-4 text-left font-semibold text-gray-900 text-[15px] leading-snug transition-colors duration-200 focus:outline-none\"\n            style=\"\">\n            <span class=\"flex items-start gap-3\">\n              <span class=\"mt-0.5 flex-shrink-0 w-6 h-6 rounded-full flex items-center justify-center text-white text-xs font-bold\"\n                    style=\"background:#0A3D2E;min-width:1.5rem\">\n                7              <\/span>\n              <span>Por que escolher 4 dias em vez de 5?<\/span>\n            <\/span>\n            <!-- \u00cdcono chevron -->\n            <svg class=\"aura-faq-icon flex-shrink-0 transition-transform duration-300 \"\n                 width=\"20\" height=\"20\" fill=\"none\" stroke=\"#9ca3af\"\n                 stroke-width=\"2.2\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M19 9l-7 7-7-7\"\/>\n            <\/svg>\n          <\/button>\n\n          <!-- Panel respuesta -->\n          <div\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-6\"\n            role=\"region\"\n            aria-labelledby=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-6\"\n            class=\"aura-faq-panel\"\n            style=\"overflow:hidden;transition:max-height .35s ease,opacity .3s ease;max-height:0;opacity:0;\">\n            <div class=\"px-5 pb-5 pt-1 border-t border-gray-100\">\n              <div class=\"aura-faq-content text-gray-600 text-[14.5px] leading-relaxed pl-9\">\n                <p>O roteiro de 4 dias \u00e9 ideal se voc\u00ea tem pouco tempo ou prefere um ritmo um pouco mais din\u00e2mico. Visitamos os mesmos pontos tur\u00edsticos deslumbrantes (Lagoa Humantay e o Passo Abra), mas otimizamos o trecho na selva. \u00c9 a dose perfeita de adrenalina e recompensa.<\/p>\n              <\/div>\n            <\/div>\n          <\/div>\n\n        <\/div>\n                <div class=\"aura-faq-item border border-gray-200 rounded-xl overflow-hidden transition-shadow hover:shadow-md bg-white mb-3\"\n             data-faq-item>\n\n          <!-- Bot\u00f3n pregunta -->\n          <button\n            type=\"button\"\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-7\"\n            aria-expanded=\"false\"\n            aria-controls=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-7\"\n            class=\"aura-faq-btn w-full flex items-center justify-between gap-4 px-5 py-4 text-left font-semibold text-gray-900 text-[15px] leading-snug transition-colors duration-200 focus:outline-none\"\n            style=\"\">\n            <span class=\"flex items-start gap-3\">\n              <span class=\"mt-0.5 flex-shrink-0 w-6 h-6 rounded-full flex items-center justify-center text-white text-xs font-bold\"\n                    style=\"background:#0A3D2E;min-width:1.5rem\">\n                8              <\/span>\n              <span>Eu realmente verei o nascer do sol em Machu Picchu?<\/span>\n            <\/span>\n            <!-- \u00cdcono chevron -->\n            <svg class=\"aura-faq-icon flex-shrink-0 transition-transform duration-300 \"\n                 width=\"20\" height=\"20\" fill=\"none\" stroke=\"#9ca3af\"\n                 stroke-width=\"2.2\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <path stroke-linecap=\"round\" stroke-linejoin=\"round\" d=\"M19 9l-7 7-7-7\"\/>\n            <\/svg>\n          <\/button>\n\n          <!-- Panel respuesta -->\n          <div\n            id=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-panel-7\"\n            role=\"region\"\n            aria-labelledby=\"faqs-block_b05c875587e580a266fdf51e95d4cbca-item-7\"\n            class=\"aura-faq-panel\"\n            style=\"overflow:hidden;transition:max-height .35s ease,opacity .3s ease;max-height:0;opacity:0;\">\n            <div class=\"px-5 pb-5 pt-1 border-t border-gray-100\">\n              <div class=\"aura-faq-content text-gray-600 text-[14.5px] leading-relaxed pl-9\">\n                <p>Esse \u00e9 o plano. Sa\u00edmos de Aguas Calientes bem cedo para estarmos entre os primeiros a entrar. Observar as nuvens se dissiparem e revelarem a cidadela \u00e9 uma daquelas experi\u00eancias que arrepiam.<\/p>\n              <\/div>\n            <\/div>\n          <\/div>\n\n        <\/div>\n            <\/div>\n    \n  <\/div>\n<\/section>\n\n\n\n<script>\n(function () {\n  var block    = document.getElementById('faqs-block_b05c875587e580a266fdf51e95d4cbca');\n  if (!block) return;\n  var faqItems = block.querySelectorAll('[data-faq-item]');\n\n  function closeItem(it) {\n    var b  = it.querySelector('.aura-faq-btn');\n    var p  = it.querySelector('.aura-faq-panel');\n    var ic = it.querySelector('.aura-faq-icon');\n    b.setAttribute('aria-expanded', 'false');\n    b.style.color     = '';\n    p.style.maxHeight = '0';\n    p.style.opacity   = '0';\n    ic.classList.remove('rotate-180');\n    ic.setAttribute('stroke', '#9ca3af');\n    it.removeAttribute('data-open');\n  }\n\n  function openItem(it) {\n    var b  = it.querySelector('.aura-faq-btn');\n    var p  = it.querySelector('.aura-faq-panel');\n    var ic = it.querySelector('.aura-faq-icon');\n    b.setAttribute('aria-expanded', 'true');\n    b.style.color     = '#0A3D2E';\n    p.style.maxHeight = p.scrollHeight + 2000 + 'px';\n    p.style.opacity   = '1';\n    ic.classList.add('rotate-180');\n    ic.setAttribute('stroke', '#0A3D2E');\n    it.setAttribute('data-open', '');\n  }\n\n  faqItems.forEach(function (item) {\n    var btn = item.querySelector('.aura-faq-btn');\n    btn.addEventListener('click', function () {\n      var isOpen = btn.getAttribute('aria-expanded') === 'true';\n      faqItems.forEach(function (other) {\n        if (other !== item) closeItem(other);\n      });\n      if (isOpen) {\n        closeItem(item);\n      } else {\n        openItem(item);\n      }\n    });\n  });\n})();\n<\/script>\n<style class=\"advgb-styles-renderer\">\n    .acc-body {\n        max-height: 0;\n        overflow: hidden;\n        transition: max-height .45s ease;\n    }\n    .acc-body.open {\n        max-height: 4000px;\n    }\n    .acc-icon {\n        transition: transform .3s;\n    }\n    .acc-btn.active .acc-icon {\n        transform: rotate(180deg);\n    }\n\n.aura-faq-content a         { color: #0A3D2E; text-decoration: underline; }\n.aura-faq-content ul        { list-style: disc; padding-left: 1.25rem; margin: .5rem 0; }\n.aura-faq-content ol        { list-style: decimal; padding-left: 1.25rem; margin: .5rem 0; }\n.aura-faq-content strong    { color: #1f2937; }\n.aura-faq-btn:focus-visible { outline: 2px solid #0A3D2E; outline-offset: 2px; }\n.aura-faq-item[data-open]   { box-shadow: 0 0 0 2px rgba(10,61,46,.15); border-color: #0A3D2E; }\n<\/style>","protected":false},"author":1,"featured_media":897,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":""},"class_list":["post-874","trekking","type-trekking","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trilha Salkantay 4 Dias para Machu Picchu - Aura Travel Experience<\/title>\n<meta name=\"description\" content=\"Fa\u00e7a a Trilha Salkantay 4 dias at\u00e9 Machu Picchu, passando por montanhas andinas, trilhas na selva alta e paisagens inesquec\u00edveis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trilha Salkantay 4 Dias para Machu Picchu - Aura Travel Experience\" \/>\n<meta property=\"og:description\" content=\"Fa\u00e7a a Trilha Salkantay 4 dias at\u00e9 Machu Picchu, passando por montanhas andinas, trilhas na selva alta e paisagens inesquec\u00edveis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Aura Travel Experience\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuraTravelExperience\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T21:10:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-Trek-a-Machu-Picchu.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/trilhas\\\/trilha-salkantay-machu-picchu-4-dias\\\/\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/trilhas\\\/trilha-salkantay-machu-picchu-4-dias\\\/\",\"name\":\"Trilha Salkantay 4 Dias para Machu Picchu - Aura Travel Experience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/trilhas\\\/trilha-salkantay-machu-picchu-4-dias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/trilhas\\\/trilha-salkantay-machu-picchu-4-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/Salkantay-Trek-a-Machu-Picchu.webp\",\"datePublished\":\"2026-04-16T23:16:26+00:00\",\"dateModified\":\"2026-05-22T21:10:09+00:00\",\"description\":\"Fa\u00e7a a Trilha Salkantay 4 dias at\u00e9 Machu Picchu, passando por montanhas andinas, trilhas na selva alta e paisagens inesquec\u00edveis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/trilhas\\\/trilha-salkantay-machu-picchu-4-dias\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/trilhas\\\/trilha-salkantay-machu-picchu-4-dias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/trilhas\\\/trilha-salkantay-machu-picchu-4-dias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/Salkantay-Trek-a-Machu-Picchu.webp\",\"contentUrl\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/Salkantay-Trek-a-Machu-Picchu.webp\",\"width\":2000,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/trilhas\\\/trilha-salkantay-machu-picchu-4-dias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trekkings\",\"item\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/trilhas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trilha Salkantay a Machu Picchu 4 Dias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/\",\"name\":\"Aura Travel Experiences\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#organization\",\"name\":\"Aura Travel Experiences\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/cropped-Logo-Aura-nuevo-png.webp\",\"contentUrl\":\"https:\\\/\\\/auratravelexperience.com\\\/wp-content\\\/uploads\\\/cropped-Logo-Aura-nuevo-png.webp\",\"width\":1149,\"height\":521,\"caption\":\"Aura Travel Experiences\"},\"image\":{\"@id\":\"https:\\\/\\\/auratravelexperience.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuraTravelExperience\",\"https:\\\/\\\/www.tiktok.com\\\/@aura_travel_experience\",\"https:\\\/\\\/www.instagram.com\\\/auratravel.experience\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@AuraTravelExperience\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trilha Salkantay 4 Dias para Machu Picchu - Aura Travel Experience","description":"Fa\u00e7a a Trilha Salkantay 4 dias at\u00e9 Machu Picchu, passando por montanhas andinas, trilhas na selva alta e paisagens inesquec\u00edveis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/","og_locale":"pt_BR","og_type":"article","og_title":"Trilha Salkantay 4 Dias para Machu Picchu - Aura Travel Experience","og_description":"Fa\u00e7a a Trilha Salkantay 4 dias at\u00e9 Machu Picchu, passando por montanhas andinas, trilhas na selva alta e paisagens inesquec\u00edveis.","og_url":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/","og_site_name":"Aura Travel Experience","article_publisher":"https:\/\/www.facebook.com\/AuraTravelExperience","article_modified_time":"2026-05-22T21:10:09+00:00","og_image":[{"width":2000,"height":800,"url":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-Trek-a-Machu-Picchu.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/","url":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/","name":"Trilha Salkantay 4 Dias para Machu Picchu - Aura Travel Experience","isPartOf":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/#primaryimage"},"image":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-Trek-a-Machu-Picchu.webp","datePublished":"2026-04-16T23:16:26+00:00","dateModified":"2026-05-22T21:10:09+00:00","description":"Fa\u00e7a a Trilha Salkantay 4 dias at\u00e9 Machu Picchu, passando por montanhas andinas, trilhas na selva alta e paisagens inesquec\u00edveis.","breadcrumb":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/#primaryimage","url":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-Trek-a-Machu-Picchu.webp","contentUrl":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-Trek-a-Machu-Picchu.webp","width":2000,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/trilha-salkantay-machu-picchu-4-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auratravelexperience.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Trekkings","item":"https:\/\/auratravelexperience.com\/pt-br\/trilhas\/"},{"@type":"ListItem","position":3,"name":"Trilha Salkantay a Machu Picchu 4 Dias"}]},{"@type":"WebSite","@id":"https:\/\/auratravelexperience.com\/pt-br\/#website","url":"https:\/\/auratravelexperience.com\/pt-br\/","name":"Aura Travel Experiences","description":"","publisher":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auratravelexperience.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/auratravelexperience.com\/pt-br\/#organization","name":"Aura Travel Experiences","url":"https:\/\/auratravelexperience.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auratravelexperience.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/cropped-Logo-Aura-nuevo-png.webp","contentUrl":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/cropped-Logo-Aura-nuevo-png.webp","width":1149,"height":521,"caption":"Aura Travel Experiences"},"image":{"@id":"https:\/\/auratravelexperience.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuraTravelExperience","https:\/\/www.tiktok.com\/@aura_travel_experience","https:\/\/www.instagram.com\/auratravel.experience\/","https:\/\/www.youtube.com\/@AuraTravelExperience"]}]}},"featured_img":"https:\/\/auratravelexperience.com\/wp-content\/uploads\/Salkantay-Trek-a-Machu-Picchu.webp","coauthors":[],"author_meta":{"author_link":"https:\/\/auratravelexperience.com\/pt-br\/author\/admin_aura\/","display_name":"admin_aura"},"relative_dates":{"created":"Publicado 3 meses atr\u00e1s","modified":"Atualizado 2 meses atr\u00e1s"},"absolute_dates":{"created":"Publicado em 16 de abril de 2026","modified":"Atualizado em 22 de maio de 2026"},"absolute_dates_time":{"created":"Publicado em 16 de abril de 2026 18:16","modified":"Atualizado em 22 de maio de 2026 16:10"},"featured_img_caption":"","tax_additional":{"translation_priority":{"linked":["<a href=\"https:\/\/auratravelexperience.com\/es\/?taxonomy=translation_priority&#038;term=opcional\" class=\"advgb-post-tax-term\">Opcional<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Opcional<\/span>"],"slug":"translation_priority","name":"Prioridades de tradu\u00e7\u00e3o"}},"series_order":"","_links":{"self":[{"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/trekking\/874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/trekking"}],"about":[{"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/types\/trekking"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/media\/897"}],"wp:attachment":[{"href":"https:\/\/auratravelexperience.com\/pt-br\/wp-json\/wp\/v2\/media?parent=874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}